{"id":7738,"date":"2024-09-18T09:32:38","date_gmt":"2024-09-18T06:32:38","guid":{"rendered":"https:\/\/eccb2024.fi\/?page_id=7738"},"modified":"2024-09-26T09:06:12","modified_gmt":"2024-09-26T06:06:12","slug":"photogallery","status":"publish","type":"page","link":"https:\/\/eccb2024.fi\/photogallery","title":{"rendered":"Photogallery"},"content":{"rendered":"[vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#bed3e0&#8243; scene_position=&#8221;center&#8221; top_padding=&#8221;8%&#8221; top_padding_phone=&#8221;1%&#8221; bottom_padding_phone=&#8221;10%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;2\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;100&#8243;][nectar_highlighted_text color_type=&#8221;regular&#8221; highlight_color=&#8221;#548eb2&#8243; style=&#8221;half_text&#8221; text_direction=&#8221;default&#8221;]\n<h2><em>Photogallery<\/em><\/h2>\n[\/nectar_highlighted_text][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; background_image=&#8221;5864&#8243; background_image_position=&#8221;center top&#8221; background_image_stacking=&#8221;default&#8221; background_image_loading=&#8221;default&#8221; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221; offset=&#8221;vc_hidden-sm vc_hidden-xs&#8221;][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;340&#8243;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;80px&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;5%&#8221; bottom_padding=&#8221;5%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_custom_heading text=&#8221;Photos from ECCB2024 conference&#8221; font_container=&#8221;tag:h3|text_align:left&#8221; use_theme_fonts=&#8221;yes&#8221; css=&#8221;&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]Photos: Studio Svarte \/ Linda Svarfvar[\/vc_column_text][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;30&#8243;][vc_gallery css=&#8221;&#8221; type=&#8221;image_grid&#8221; images=&#8221;7849,7848,7850,7845,7846,7847,7851,7749,7753,7844,7843,7853,7854,7852,7745,7743,7744,7740,7879,7881,7788,7785,7878,7882,7877,7876,7874,7875,7873,7872,7871,7870,7883,7886,7869,7868,7867,7864,7865,7863,7862,7884,7885,7861,7860,7859,7857,7858,7856,7855,7894,7895,7889,7893,7892,7891,7890,7887,7888,7896,7897,7898,7899,7827,7824,7823,7838,7835,7904,7905,7906,7907&#8243; image_grid_loading=&#8221;default&#8221; layout=&#8221;4&#8243; item_spacing=&#8221;5px&#8221; gallery_style=&#8221;7&#8243; load_in_animation=&#8221;fade_in&#8221;][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#bed3e0&#8243; scene_position=&#8221;center&#8221; top_padding=&#8221;8%&#8221; top_padding_phone=&#8221;1%&#8221; bottom_padding_phone=&#8221;10%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221;&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-7738","page","type-page","status-publish"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Photogallery - ECCB2024<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eccb2024.fi\/photogallery\" \/>\n<meta property=\"og:locale\" content=\"fi_FI\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Photogallery - ECCB2024\" \/>\n<meta property=\"og:description\" content=\"[vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#bed3e0&#8243; scene_position=&#8221;center&#8221; top_padding=&#8221;8%&#8221; top_padding_phone=&#8221;1%&#8221; bottom_padding_phone=&#8221;10%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221;...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eccb2024.fi\/photogallery\" \/>\n<meta property=\"og:site_name\" content=\"ECCB2024\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-26T06:06:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/eccb2024.fi\/wp-content\/uploads\/2024\/01\/ECCB2024-esikatselukuva2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Arvioitu lukuaika\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuutti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/eccb2024.fi\/photogallery\",\"url\":\"https:\/\/eccb2024.fi\/photogallery\",\"name\":\"Photogallery - ECCB2024\",\"isPartOf\":{\"@id\":\"https:\/\/eccb2024.fi\/#website\"},\"datePublished\":\"2024-09-18T06:32:38+00:00\",\"dateModified\":\"2024-09-26T06:06:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/eccb2024.fi\/photogallery#breadcrumb\"},\"inLanguage\":\"fi\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/eccb2024.fi\/photogallery\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/eccb2024.fi\/photogallery#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Etusivu\",\"item\":\"https:\/\/eccb2024.fi\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Photogallery\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/eccb2024.fi\/#website\",\"url\":\"https:\/\/eccb2024.fi\/\",\"name\":\"ECCB2024\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/eccb2024.fi\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/eccb2024.fi\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fi\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/eccb2024.fi\/#organization\",\"name\":\"ECCB2024\",\"url\":\"https:\/\/eccb2024.fi\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fi\",\"@id\":\"https:\/\/eccb2024.fi\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/eccb2024.fi\/wp-content\/uploads\/2022\/09\/eccb2024-logo_800px.png\",\"contentUrl\":\"https:\/\/eccb2024.fi\/wp-content\/uploads\/2022\/09\/eccb2024-logo_800px.png\",\"width\":800,\"height\":493,\"caption\":\"ECCB2024\"},\"image\":{\"@id\":\"https:\/\/eccb2024.fi\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Photogallery - ECCB2024","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/eccb2024.fi\/photogallery","og_locale":"fi_FI","og_type":"article","og_title":"Photogallery - ECCB2024","og_description":"[vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#bed3e0&#8243; scene_position=&#8221;center&#8221; top_padding=&#8221;8%&#8221; top_padding_phone=&#8221;1%&#8221; bottom_padding_phone=&#8221;10%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221;...","og_url":"https:\/\/eccb2024.fi\/photogallery","og_site_name":"ECCB2024","article_modified_time":"2024-09-26T06:06:12+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/eccb2024.fi\/wp-content\/uploads\/2024\/01\/ECCB2024-esikatselukuva2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Arvioitu lukuaika":"1 minuutti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/eccb2024.fi\/photogallery","url":"https:\/\/eccb2024.fi\/photogallery","name":"Photogallery - ECCB2024","isPartOf":{"@id":"https:\/\/eccb2024.fi\/#website"},"datePublished":"2024-09-18T06:32:38+00:00","dateModified":"2024-09-26T06:06:12+00:00","breadcrumb":{"@id":"https:\/\/eccb2024.fi\/photogallery#breadcrumb"},"inLanguage":"fi","potentialAction":[{"@type":"ReadAction","target":["https:\/\/eccb2024.fi\/photogallery"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/eccb2024.fi\/photogallery#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Etusivu","item":"https:\/\/eccb2024.fi\/"},{"@type":"ListItem","position":2,"name":"Photogallery"}]},{"@type":"WebSite","@id":"https:\/\/eccb2024.fi\/#website","url":"https:\/\/eccb2024.fi\/","name":"ECCB2024","description":"","publisher":{"@id":"https:\/\/eccb2024.fi\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/eccb2024.fi\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fi"},{"@type":"Organization","@id":"https:\/\/eccb2024.fi\/#organization","name":"ECCB2024","url":"https:\/\/eccb2024.fi\/","logo":{"@type":"ImageObject","inLanguage":"fi","@id":"https:\/\/eccb2024.fi\/#\/schema\/logo\/image\/","url":"https:\/\/eccb2024.fi\/wp-content\/uploads\/2022\/09\/eccb2024-logo_800px.png","contentUrl":"https:\/\/eccb2024.fi\/wp-content\/uploads\/2022\/09\/eccb2024-logo_800px.png","width":800,"height":493,"caption":"ECCB2024"},"image":{"@id":"https:\/\/eccb2024.fi\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/eccb2024.fi\/wp-json\/wp\/v2\/pages\/7738"}],"collection":[{"href":"https:\/\/eccb2024.fi\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/eccb2024.fi\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/eccb2024.fi\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eccb2024.fi\/wp-json\/wp\/v2\/comments?post=7738"}],"version-history":[{"count":24,"href":"https:\/\/eccb2024.fi\/wp-json\/wp\/v2\/pages\/7738\/revisions"}],"predecessor-version":[{"id":7911,"href":"https:\/\/eccb2024.fi\/wp-json\/wp\/v2\/pages\/7738\/revisions\/7911"}],"wp:attachment":[{"href":"https:\/\/eccb2024.fi\/wp-json\/wp\/v2\/media?parent=7738"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}