{"id":6197,"date":"2023-06-05T09:32:24","date_gmt":"2023-06-05T06:32:24","guid":{"rendered":"https:\/\/eccb2024.fi\/?page_id=6197"},"modified":"2024-09-15T19:17:39","modified_gmt":"2024-09-15T16:17:39","slug":"conference-programme","status":"publish","type":"page","link":"https:\/\/eccb2024.fi\/conference-programme","title":{"rendered":"Conference programme"},"content":{"rendered":"[vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#bed3e0&#8243; scene_position=&#8221;center&#8221; top_padding=&#8221;8%&#8221; top_padding_phone=&#8221;1%&#8221; bottom_padding_phone=&#8221;10%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;2\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;100&#8243;][nectar_highlighted_text color_type=&#8221;regular&#8221; highlight_color=&#8221;#548eb2&#8243; style=&#8221;half_text&#8221;]\n<h2><em>Conference programme<\/em><\/h2>\n[\/nectar_highlighted_text][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; background_image=&#8221;5864&#8243; background_image_position=&#8221;center top&#8221; background_image_stacking=&#8221;default&#8221; background_image_loading=&#8221;default&#8221; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221; offset=&#8221;vc_hidden-sm vc_hidden-xs&#8221;][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;340&#8243;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;3%&#8221; constrain_group_1=&#8221;yes&#8221; bottom_padding=&#8221;3%&#8221; top_padding_phone=&#8221;10%&#8221; constrain_group_5=&#8221;yes&#8221; bottom_padding_phone=&#8221;10%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<h4>Programme<\/h4>\n<p><em>(Embedded from the Oxford Abstracts system, no need to sign in to view the public programme. Conference participants have been sent the sign in link to vie the full programme with absracts.)<br \/>\n<\/em><\/p>\n<ul>\n<li>To search by presenter name, select \u201dparticipants\u201d from the left-hand sidebar and enter the name of the presenter in the search field.<\/li>\n<\/ul>\n<p><em>\u00a0<\/em>[\/vc_column_text][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;20&#8243; custom_height_phone=&#8221;0&#8243;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<div style=\"padding-bottom: 130%; position: relative; display: block; width: 100%;\"><iframe loading=\"lazy\" style=\"position: absolute; top: 0; left: 0;\" src=\"https:\/\/virtual.oxfordabstracts.com\/#\/event\/public\/5223\/program\" width=\"100%\" height=\"100%\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><br \/>\n<\/iframe><\/div>\n[\/vc_column_text][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;50&#8243;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]<strong>Programme codes:<\/strong> OP=proceedings talk, OH=Highlight talk, OE=Elixir track talk, P=Posters<\/p>\n<p><em>Note that the programme is subject to changes.<\/em>[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;3%&#8221; constrain_group_1=&#8221;yes&#8221; bottom_padding=&#8221;3%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; disable_element=&#8221;yes&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][tabbed_section style=&#8221;minimal&#8221; tab_change_animation=&#8221;fade&#8221; alignment=&#8221;left&#8221; spacing=&#8221;default&#8221; tab_color=&#8221;Extra-Color-1&#8243; vs_content_animation=&#8221;fade&#8221; vs_link_animation=&#8221;opacity&#8221; vs_navigation_alignment=&#8221;left&#8221; vs_navigation_width_2=&#8221;25%&#8221; vs_navigation_func=&#8221;default&#8221; vs_navigation_width=&#8221;regular&#8221; vs_navigation_spacing=&#8221;15px&#8221; vs_navigation_mobile_display=&#8221;visible&#8221; vs_tab_spacing=&#8221;5%&#8221; cta_button_style=&#8221;accent-color&#8221; icon_size=&#8221;24&#8243;][tab icon_family=&#8221;none&#8221; title=&#8221;16 September&#8221; id=&#8221;1726416969320-0&#8243; tab_id=&#8221;1726416969321-0&#8243;][vc_column_text]\n<table id=\"tablepress-1\" class=\"tablepress tablepress-id-1\">\n<thead>\n<tr class=\"row-1 odd\">\n\t<th class=\"column-1\">Time<\/th><th class=\"column-2\"><\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-hover\">\n<tr class=\"row-2 even\">\n\t<td class=\"column-1\">9:00\u2013<\/td><td class=\"column-2\"><\/td>\n<\/tr>\n<tr class=\"row-3 odd\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\"><\/td>\n<\/tr>\n<tr class=\"row-4 even\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\"><\/td>\n<\/tr>\n<tr class=\"row-5 odd\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\"><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<!-- #tablepress-1 from cache -->[\/vc_column_text][\/tab][tab icon_family=&#8221;none&#8221; title=&#8221;17 September&#8221; id=&#8221;1726416969340-6&#8243; tab_id=&#8221;1726416969341-1&#8243;][vc_column_text][\/vc_column_text][\/tab][tab icon_family=&#8221;none&#8221; title=&#8221;18 September&#8221; id=&#8221;1726416969357-1&#8243; tab_id=&#8221;1726416969357-4&#8243;][vc_column_text][\/vc_column_text][\/tab][tab icon_family=&#8221;none&#8221; title=&#8221;19 September&#8221; id=&#8221;1726416969367-4&#8243; tab_id=&#8221;1726416969368-6&#8243;][vc_column_text][\/vc_column_text][\/tab][tab icon_family=&#8221;none&#8221; title=&#8221;20 September&#8221; id=&#8221;1726416969378-3&#8243; tab_id=&#8221;1726416969378-4&#8243;][vc_column_text][\/vc_column_text][\/tab][\/tabbed_section][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#bed3e0&#8243; scene_position=&#8221;center&#8221; top_padding=&#8221;8%&#8221; top_padding_phone=&#8221;1%&#8221; bottom_padding_phone=&#8221;10%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221;&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-6197","page","type-page","status-publish"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Conference programme - ECCB2024<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eccb2024.fi\/conference-programme\" \/>\n<meta property=\"og:locale\" content=\"fi_FI\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Conference programme - ECCB2024\" \/>\n<meta property=\"og:description\" content=\"[vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#bed3e0&#8243; scene_position=&#8221;center&#8221; top_padding=&#8221;8%&#8221; top_padding_phone=&#8221;1%&#8221; bottom_padding_phone=&#8221;10%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221;...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eccb2024.fi\/conference-programme\" \/>\n<meta property=\"og:site_name\" content=\"ECCB2024\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-15T16:17:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/eccb2024.fi\/wp-content\/uploads\/2024\/01\/ECCB2024-esikatselukuva2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Arvioitu lukuaika\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minuuttia\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/eccb2024.fi\/conference-programme\",\"url\":\"https:\/\/eccb2024.fi\/conference-programme\",\"name\":\"Conference programme - ECCB2024\",\"isPartOf\":{\"@id\":\"https:\/\/eccb2024.fi\/#website\"},\"datePublished\":\"2023-06-05T06:32:24+00:00\",\"dateModified\":\"2024-09-15T16:17:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/eccb2024.fi\/conference-programme#breadcrumb\"},\"inLanguage\":\"fi\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/eccb2024.fi\/conference-programme\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/eccb2024.fi\/conference-programme#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Etusivu\",\"item\":\"https:\/\/eccb2024.fi\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Conference programme\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/eccb2024.fi\/#website\",\"url\":\"https:\/\/eccb2024.fi\/\",\"name\":\"ECCB2024\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/eccb2024.fi\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/eccb2024.fi\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fi\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/eccb2024.fi\/#organization\",\"name\":\"ECCB2024\",\"url\":\"https:\/\/eccb2024.fi\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fi\",\"@id\":\"https:\/\/eccb2024.fi\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/eccb2024.fi\/wp-content\/uploads\/2022\/09\/eccb2024-logo_800px.png\",\"contentUrl\":\"https:\/\/eccb2024.fi\/wp-content\/uploads\/2022\/09\/eccb2024-logo_800px.png\",\"width\":800,\"height\":493,\"caption\":\"ECCB2024\"},\"image\":{\"@id\":\"https:\/\/eccb2024.fi\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Conference programme - ECCB2024","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/eccb2024.fi\/conference-programme","og_locale":"fi_FI","og_type":"article","og_title":"Conference programme - ECCB2024","og_description":"[vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#bed3e0&#8243; scene_position=&#8221;center&#8221; top_padding=&#8221;8%&#8221; top_padding_phone=&#8221;1%&#8221; bottom_padding_phone=&#8221;10%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221;...","og_url":"https:\/\/eccb2024.fi\/conference-programme","og_site_name":"ECCB2024","article_modified_time":"2024-09-15T16:17:39+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/eccb2024.fi\/wp-content\/uploads\/2024\/01\/ECCB2024-esikatselukuva2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Arvioitu lukuaika":"3 minuuttia"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/eccb2024.fi\/conference-programme","url":"https:\/\/eccb2024.fi\/conference-programme","name":"Conference programme - ECCB2024","isPartOf":{"@id":"https:\/\/eccb2024.fi\/#website"},"datePublished":"2023-06-05T06:32:24+00:00","dateModified":"2024-09-15T16:17:39+00:00","breadcrumb":{"@id":"https:\/\/eccb2024.fi\/conference-programme#breadcrumb"},"inLanguage":"fi","potentialAction":[{"@type":"ReadAction","target":["https:\/\/eccb2024.fi\/conference-programme"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/eccb2024.fi\/conference-programme#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Etusivu","item":"https:\/\/eccb2024.fi\/"},{"@type":"ListItem","position":2,"name":"Conference programme"}]},{"@type":"WebSite","@id":"https:\/\/eccb2024.fi\/#website","url":"https:\/\/eccb2024.fi\/","name":"ECCB2024","description":"","publisher":{"@id":"https:\/\/eccb2024.fi\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/eccb2024.fi\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fi"},{"@type":"Organization","@id":"https:\/\/eccb2024.fi\/#organization","name":"ECCB2024","url":"https:\/\/eccb2024.fi\/","logo":{"@type":"ImageObject","inLanguage":"fi","@id":"https:\/\/eccb2024.fi\/#\/schema\/logo\/image\/","url":"https:\/\/eccb2024.fi\/wp-content\/uploads\/2022\/09\/eccb2024-logo_800px.png","contentUrl":"https:\/\/eccb2024.fi\/wp-content\/uploads\/2022\/09\/eccb2024-logo_800px.png","width":800,"height":493,"caption":"ECCB2024"},"image":{"@id":"https:\/\/eccb2024.fi\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/eccb2024.fi\/wp-json\/wp\/v2\/pages\/6197"}],"collection":[{"href":"https:\/\/eccb2024.fi\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/eccb2024.fi\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/eccb2024.fi\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eccb2024.fi\/wp-json\/wp\/v2\/comments?post=6197"}],"version-history":[{"count":102,"href":"https:\/\/eccb2024.fi\/wp-json\/wp\/v2\/pages\/6197\/revisions"}],"predecessor-version":[{"id":7690,"href":"https:\/\/eccb2024.fi\/wp-json\/wp\/v2\/pages\/6197\/revisions\/7690"}],"wp:attachment":[{"href":"https:\/\/eccb2024.fi\/wp-json\/wp\/v2\/media?parent=6197"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}